{"id":183,"date":"2023-07-13T09:29:05","date_gmt":"2023-07-13T07:29:05","guid":{"rendered":"https:\/\/ambnairobi.esteri.it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/albo-consolare-e-altri-servizi\/pubblicazioni-albo-consolare\/"},"modified":"2023-07-13T09:51:07","modified_gmt":"2023-07-13T07:51:07","slug":"pubblicazioni-albo-consolare","status":"publish","type":"page","link":"https:\/\/ambnairobi.esteri.it\/en\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/albo-consolare-e-altri-servizi\/pubblicazioni-albo-consolare\/","title":{"rendered":"Consular register publications"},"content":{"rendered":"\t\t<div id=\"collapseDiv1\" class=\"accordion accordion-background-active\">\r\n\t\t\t\t\t\t<div class=\"accordion-item\">\r\n\t\t\t\t<h2 class=\"accordion-header\" id=\"heading2\">\r\n\t\t\t\t\t<button class=\"accordion-button\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse2\" aria-expanded=\"false\" aria-controls=\"collapse2\">\r\n\t\t\t\t\t\tCambioNome\t\t\t\t\t<\/button>\r\n\t\t\t\t<\/h2>\r\n\t\t\t\t<div id=\"collapse2\" class=\"accordion-collapse collapse \" data-bs-parent=\"collapseDiv1\" role=\"region\" aria-labelledby=\"heading2\">\r\n\t\t\t\t\t<div class=\"collapse-body p-2\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<p>\r\n\t\t\t\t\t\t\tPubblicato il 14-08-2026 -\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/ambnairobi.esteri.it\/wp-content\/uploads\/pubblicazioni\/avviso di cambio nome di minore.pdf\" title=\"Scarica il documento Luna Rencuzogullari - cambio cognome\">Luna Rencuzogullari - cambio cognome<\/a>\r\n\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.collapse-body -->\r\n\t\t\t\t<\/div><!-- \/.accordion-collapse -->\r\n\t\t\t<\/div><!-- \/.accordion-item -->\r\n\t\t\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":182,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-183","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/pages\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":1,"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/pages\/183\/revisions"}],"predecessor-version":[{"id":235,"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/pages\/183\/revisions\/235"}],"up":[{"embeddable":true,"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/pages\/182"}],"wp:attachment":[{"href":"https:\/\/ambnairobi.esteri.it\/en\/wp-json\/wp\/v2\/media?parent=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}